{"id":34358,"date":"2018-08-22T07:30:55","date_gmt":"2018-08-22T07:30:55","guid":{"rendered":"http:\/\/fotos.costabrava.org\/downloads\/catedral-de-girona-i-basilica-de-sant-felix\/"},"modified":"2018-08-22T07:43:02","modified_gmt":"2018-08-22T07:43:02","slug":"catedral-de-girona-i-basilica-de-sant-felix","status":"publish","type":"download","link":"https:\/\/fotos.costabrava.org\/fr\/downloads\/catedral-de-girona-i-basilica-de-sant-felix\/","title":{"rendered":"Cath\u00e9drale de G\u00e9rone et \u00c9glise Sant F\u00e8lix"},"content":{"rendered":"<p>Cath\u00e9drale de G\u00e9rone et \u00c9glise Sant F\u00e8lix<\/p>\n<ul style=\"padding-left: 30px; font-size: 12px;\">\n<li>Photo: \u00c0lex Tremps<\/li>\n<li>Localit\u00e9: Girona<\/li>\n<li>Commune: Girona<\/li>\n<li>R\u00e9gion:  Giron\u00e8s<\/li>\n<li>Cat\u00e9gorie: Costa Brava, Villages<\/li>\n<li>Tags: Girona, Giron\u00e8s, Villages<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cath\u00e9drale de G\u00e9rone et \u00c9glise Sant F\u00e8lix Photo: \u00c0lex Tremps Localit\u00e9: Girona Commune: Girona R\u00e9gion: Giron\u00e8s Cat\u00e9gorie: Costa Brava, Villages [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34344,"template":"","edd-categories":[33,983],"edd-tags":[2355,502,2375,673],"class_list":["post-34358","download","type-download","status-publish","has-post-thumbnail","hentry","download_category-costa-brava-fr","download_category-villages-fr","download_tag-cathedrale-de-gerone-fr","download_tag-girona-fr","download_tag-sant-felix-fr","download_tag-villages-fr","edd-download","edd-download-cat-costa-brava-fr","edd-download-cat-villages-fr","edd-download-tag-cathedrale-de-gerone-fr","edd-download-tag-girona-fr","edd-download-tag-sant-felix-fr","edd-download-tag-villages-fr"],"_links":{"self":[{"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/edd-downloads\/34358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/edd-downloads"}],"about":[{"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/types\/download"}],"author":[{"embeddable":true,"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/edd-downloads\/34358\/revisions"}],"predecessor-version":[{"id":34360,"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/edd-downloads\/34358\/revisions\/34360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/media\/34344"}],"wp:attachment":[{"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/media?parent=34358"}],"wp:term":[{"taxonomy":"download_category","embeddable":true,"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/edd-categories?post=34358"},{"taxonomy":"download_tag","embeddable":true,"href":"https:\/\/fotos.costabrava.org\/fr\/wp-json\/wp\/v2\/edd-tags?post=34358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}